{"id":680,"date":"2021-05-05T08:38:00","date_gmt":"2021-05-05T08:38:00","guid":{"rendered":"https:\/\/ibkrcampus.eu\/glossary-terms\/compx\/"},"modified":"2021-05-05T08:38:00","modified_gmt":"2021-05-05T08:38:00","slug":"compx","status":"publish","type":"glossary-terms","link":"https:\/\/www.interactivebrokers.eu\/campus\/glossary-terms\/compx\/","title":{"rendered":"COMPX"},"content":{"rendered":"<p>The symbol for the\u00a0NASDAQ\u00a0Composite Index.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The symbol for the\u00a0NASDAQ\u00a0Composite Index.<\/p>\n","protected":false},"featured_media":0,"parent":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"traders-glossary":[162,157],"class_list":["post-680","glossary-terms","type-glossary-terms","status-publish","traders-glossary-trading-terms-c","traders-glossary-trading-alphabet"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Archives Term | IBKR Glossary | IBKR Campus<\/title>\n<meta name=\"description\" content=\"The symbol for the\u00a0NASDAQ\u00a0Composite Index.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMPX\" \/>\n<meta property=\"og:description\" content=\"The symbol for the\u00a0NASDAQ\u00a0Composite Index.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/\" \/>\n<meta property=\"og:site_name\" content=\"IBKR Campus EU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\\\/\\\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"WebPage\",\n\t            \"@id\": \"https:\\\/\\\/www.interactivebrokers.eu\\\/campus\\\/glossary-terms\\\/compx\\\/\",\n\t            \"url\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/compx\\\/\",\n\t            \"name\": \"COMPX\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\\\/\\\/ibkrcampus.eu\\\/campus\\\/#website\"\n\t            },\n\t            \"datePublished\": \"2021-05-05T08:38:00+00:00\",\n\t            \"description\": \"The symbol for the\u00a0NASDAQ\u00a0Composite Index.\",\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/compx\\\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"en-US\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"ReadAction\",\n\t                    \"target\": [\n\t                        \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/compx\\\/\"\n\t                    ]\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\\\/\\\/www.interactivebrokers.com\\\/campus\\\/glossary-terms\\\/compx\\\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\\\/\\\/www.interactivebrokers.eu\\\/campus\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Glossary\",\n\t                    \"item\": \"https:\\\/\\\/www.interactivebrokers.eu\\\/campus\\\/glossary-terms\\\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"COMPX\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\\\/\\\/ibkrcampus.eu\\\/campus\\\/#website\",\n\t            \"url\": \"https:\\\/\\\/ibkrcampus.eu\\\/campus\\\/\",\n\t            \"name\": \"IBKR Campus EU\",\n\t            \"description\": \"\",\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\\\/\\\/ibkrcampus.eu\\\/campus\\\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"en-US\"\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Archives Term | IBKR Glossary | IBKR Campus","description":"The symbol for the\u00a0NASDAQ\u00a0Composite Index.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/","og_locale":"en_US","og_type":"article","og_title":"COMPX","og_description":"The symbol for the\u00a0NASDAQ\u00a0Composite Index.","og_url":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/","og_site_name":"IBKR Campus EU","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.interactivebrokers.eu\/campus\/glossary-terms\/compx\/","url":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/","name":"COMPX","isPartOf":{"@id":"https:\/\/ibkrcampus.eu\/campus\/#website"},"datePublished":"2021-05-05T08:38:00+00:00","description":"The symbol for the\u00a0NASDAQ\u00a0Composite Index.","breadcrumb":{"@id":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.interactivebrokers.com\/campus\/glossary-terms\/compx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.interactivebrokers.eu\/campus\/"},{"@type":"ListItem","position":2,"name":"Glossary","item":"https:\/\/www.interactivebrokers.eu\/campus\/glossary-terms\/"},{"@type":"ListItem","position":3,"name":"COMPX"}]},{"@type":"WebSite","@id":"https:\/\/ibkrcampus.eu\/campus\/#website","url":"https:\/\/ibkrcampus.eu\/campus\/","name":"IBKR Campus EU","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibkrcampus.eu\/campus\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/ibkrcampus.eu\/campus\/wp-json\/wp\/v2\/glossary-terms\/680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibkrcampus.eu\/campus\/wp-json\/wp\/v2\/glossary-terms"}],"about":[{"href":"https:\/\/ibkrcampus.eu\/campus\/wp-json\/wp\/v2\/types\/glossary-terms"}],"version-history":[{"count":0,"href":"https:\/\/ibkrcampus.eu\/campus\/wp-json\/wp\/v2\/glossary-terms\/680\/revisions"}],"wp:attachment":[{"href":"https:\/\/ibkrcampus.eu\/campus\/wp-json\/wp\/v2\/media?parent=680"}],"wp:term":[{"taxonomy":"traders-glossary","embeddable":true,"href":"https:\/\/ibkrcampus.eu\/campus\/wp-json\/wp\/v2\/traders-glossary?post=680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}